{"id":987513440,"date":"2024-11-16T21:02:44","date_gmt":"2024-11-16T21:02:44","guid":{"rendered":"https:\/\/saharacameltours.com\/project\/tour-de-3-dias-desde-fez-al-desierto-de-merzouga-con-regreso-a-fez\/"},"modified":"2025-11-20T09:07:33","modified_gmt":"2025-11-20T09:07:33","slug":"tour-de-3-dias-desde-fez-al-desierto-de-merzouga-con-regreso-a-fez","status":"publish","type":"project","link":"https:\/\/saharacameltours.com\/es\/project\/tour-de-3-dias-desde-fez-al-desierto-de-merzouga-con-regreso-a-fez\/","title":{"rendered":"Tour de 3 D\u00edas desde Fez al Desierto de Merzouga con regreso a Fez"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#B3B3B3&#8243; background_image=&#8221;https:\/\/saharacameltours.com\/wp-content\/uploads\/2024\/11\/FES.jpg&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;232px||232px||true|false&#8221; custom_padding_tablet=&#8221;178px||178px||true|false&#8221; custom_padding_phone=&#8221;59px||59px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/saharacameltours.com\/wp-content\/uploads\/2024\/11\/dividerss.png&#8221; title_text=&#8221;separadores&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;50%&#8221; width_tablet=&#8221;50%&#8221; width_phone=&#8221;58%&#8221; width_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Prata|700||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#EDF000&#8243; title_font_size=&#8221;48px&#8221; title_line_height=&#8221;1.5em&#8221; hover_enabled=&#8221;0&#8243; title_font_size_tablet=&#8221;33px&#8221; title_font_size_phone=&#8221;27px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; title_line_height_tablet=&#8221;1.2em&#8221; title_line_height_phone=&#8221;1.3em&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_post_title][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjM1IiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@&#8221; button_text=&#8221;Reserve esta excursi\u00f3n&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.3&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;|700||on|||||&#8221; custom_padding=&#8221;20px|40px|20px|40px|true|true&#8221; custom_padding_tablet=&#8221;20px|40px|20px|40px|true|true&#8221; custom_padding_phone=&#8221;16px|36px|16px|36px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#B3B3B3&#8243; custom_padding=&#8221;|25px||25px|false|true&#8221; custom_padding_tablet=&#8221;|25px||25px|false|true&#8221; custom_padding_phone=&#8221;18px|10px|18px|10px|true|true&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Resumen del Tour de 3 D\u00edas desde Fez a Merzouga:&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe012;||divi||400&#8243; icon_color=&#8221;#d1cfbb&#8221; image_icon_width=&#8221;42px&#8221; icon_alignment=&#8221;left&#8221; image_icon_width_tablet=&#8221;42px&#8221; image_icon_width_phone=&#8221;32px&#8221; image_icon_width_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;Prata|700||on|||||&#8221; header_text_color=&#8221;gcid-9464c34f-f9ff-43eb-9668-c958662e33fc&#8221; header_font_size=&#8221;23px&#8221; body_font=&#8221;Poppins|500|||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; body_font_size=&#8221;16px&#8221; background_color=&#8221;#474747&#8243; custom_padding=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_tablet=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_phone=&#8221;15px|10px|0px|10px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;23px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; body_font_size_tablet=&#8221;12px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;&#8221; body_line_height_phone=&#8221;1.8em&#8221; body_line_height_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{%22gcid-9464c34f-f9ff-43eb-9668-c958662e33fc%22:%91%22header_text_color%22%93}&#8221;]<\/p>\n<p><span style=\"color: #ffffff;\">Comienza tu inolvidable aventura de 3 d\u00edas desde Fez hasta el desierto del Sahara y de regreso.<br \/>El D\u00eda 1, el viaje empieza con un recorrido panor\u00e1mico por Ifrane y los bosques de cedros de Azrou, donde ver\u00e1s monos salvajes. Contin\u00faa cruzando las Monta\u00f1as del Atlas, disfrutando de paisajes impresionantes, y haz una parada para almorzar en el pueblo bereber de Zaida. M\u00e1s tarde, llegar\u00e1s a las Gargantas del Todra al atardecer.<br \/>El D\u00eda 2, viaja desde las Gargantas del Todra hasta Merzouga, pasando por encantadores pueblos bereberes y notando la transici\u00f3n hacia el desierto del Sahara. En Merzouga, disfruta de un paseo en camello por las dunas de Erg Chebbi, donde presenciar\u00e1s una puesta de sol fascinante antes de pasar la noche en un campamento tradicional en el desierto.<br \/>El D\u00eda 3, despi\u00e9rtate temprano para contemplar el amanecer y luego regresa en camello a Merzouga. Despu\u00e9s del desayuno, vuelve a Fez pasando por el Valle del Ziz y las Monta\u00f1as del Medio Atlas, llegando por la tarde a Fez.       <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Destacados del tour de 3 d\u00edas de Fez a Merzouga:&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x64;||divi||400&#8243; icon_color=&#8221;#082125&#8243; image_icon_width=&#8221;42px&#8221; icon_alignment=&#8221;left&#8221; image_icon_width_tablet=&#8221;42px&#8221; image_icon_width_phone=&#8221;32px&#8221; image_icon_width_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;Prata|700||on|||||&#8221; header_text_color=&#8221;#082125&#8243; header_font_size=&#8221;23px&#8221; body_font=&#8221;Poppins|500|||||||&#8221; body_text_color=&#8221;#424242&#8243; body_font_size=&#8221;16px&#8221; background_color=&#8221;#d1cfbb&#8221; custom_padding=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_tablet=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_phone=&#8221;15px|10px|0px|10px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;23px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;12px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;&#8221; body_line_height_phone=&#8221;1.2em&#8221; body_line_height_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Ifrane y Azrou: Comienza tu viaje con una parada en Ifrane, conocida como la &#8220;Suiza de Marruecos&#8221;, y contin\u00faa hacia los bosques de cedros de Azrou para ver monos salvajes en su h\u00e1bitat natural.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Imponentes Monta\u00f1as del Atlas: Conduce a trav\u00e9s de los hermosos paisajes de las Monta\u00f1as del Atlas, incluyendo el pueblo bereber de Zaida y la pintoresca localidad de Rich.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Gargantas del Todra: Marav\u00edllate con los imponentes acantilados y el exuberante valle de las Gargantas del Todra, perfecto para la fotograf\u00eda y el senderismo.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Paseo en camello por las dunas de Erg Chebbi: Experimenta la serenidad del Sahara con un recorrido en camello por las famosas dunas de Erg Chebbi, culminando con una impresionante puesta de sol sobre el vasto paisaje des\u00e9rtico.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Campamento tradicional en el desierto: Pasa la noche en un campamento des\u00e9rtico al estilo bereber, con una deliciosa cena, m\u00fasica y un cielo estrellado.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Amanecer sobre las dunas: Madruga para contemplar un impresionante amanecer en el desierto, seguido de un paseo en camello de regreso a Merzouga.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\">Valle del Ziz y Monta\u00f1as del Medio Atlas: Recorre el pintoresco Valle del Ziz y disfruta de los paisajes de las Monta\u00f1as del Medio Atlas mientras regresas a Fez.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_2_font=&#8221;Prata|700||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#082125&#8243; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;29px||29px||true|false&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Itinerario del Tour de 3 D\u00edas desde Fez al Desierto de Merzouga<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; header_3_font=&#8221;Prata|600||on|||||&#8221; header_3_text_align=&#8221;left&#8221; header_3_text_color=&#8221;#3f3f3f&#8221; header_3_line_height=&#8221;1.1em&#8221; header_4_font=&#8221;Noto Serif Georgian|600|||||||&#8221; header_4_font_size=&#8221;22px&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6549197a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6549197a\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-21c3aee4\" data-id=\"21c3aee4\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-68a2b48b elementor-widget elementor-widget-heading\" data-id=\"68a2b48b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\" style=\"text-align: left;\">D\u00eda 1: Fez &#8211; Midelt &#8211; Gargantas del Todra<\/h3>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-6fff4e3e elementor-widget elementor-widget-text-editor\" data-id=\"6fff4e3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"text-align: left;\">\n<div class=\"elementor-widget-container\">\n<p>Despu\u00e9s del desayuno, salida de<a href=\"https:\/\/whc.unesco.org\/en\/list\/170\" target=\"_blank\" rel=\"noopener\"> Fez<\/a> hacia las Gargantas del Todra, pasando por Ifrane hasta llegar a los bosques de cedros de Azrou, donde se encuentran los monos salvajes. Ser\u00e1 una buena oportunidad para tomar fotos de la naturaleza en Marruecos. Almuerzo en el peque\u00f1o pueblo bereber de Zaida. Continuamos el camino a trav\u00e9s de las Monta\u00f1as del Atlas, disfrutando de los paisajes de Midelt hasta llegar al peque\u00f1o pueblo de Rich. Aqu\u00ed, giramos a la derecha para pasar por la famosa localidad de Imilchil antes de llegar a las Gargantas del Todra por la tarde.    <\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3eb435c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3eb435c1\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-493526c6\" data-id=\"493526c6\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-492053bb elementor-widget elementor-widget-heading\" data-id=\"492053bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\" style=\"text-align: left;\"><i class=\"fas fa-map-marked-alt\"><\/i>D\u00eda 2: Gargantas del Todra &#8211; Merzouga (Noche en un campamento en el desierto)<\/h3>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-6a87a25 elementor-widget elementor-widget-text-editor\" data-id=\"6a87a25\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\" style=\"text-align: left;\">\n<div class=\"elementor-widget-container\">\n<p>After breakfast, we go from Toudra Gorges to Merzouga. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Berbers\" target=\"_blank\" rel=\"noopener\">Berber<\/a> villages are scattered along the way. We\u2019ll pass through Tinjdad, Jorf, and Erfoud in which we\u2019ll feel the beginning of the Saharan oasis of Tafilalet. And then continue to Merzouga, after relaxing in Merzouga, we go to ride the camels in the dunes of erg Chebbi. It is a great experience to imagine yourself riding a camel in Erg Chebbi, where the silence of the desert is the dominant. Before we reach the camp, we leave the camels and walk to a high dune to see the sunset.    <\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-526d097b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"526d097b\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2c1263e0\" data-id=\"2c1263e0\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-72ce4225 elementor-widget elementor-widget-heading\" data-id=\"72ce4225\" data-element_type=\"widget\" data-widget_type=\"heading.default\" style=\"text-align: left;\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\">D\u00eda 3: Erg Chebbi Sahara &#8211; Errachidia &#8211; Valle del Ziz &#8211; Fez<\/h3>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-2fe98cc9 elementor-widget elementor-widget-text-editor\" data-id=\"2fe98cc9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"nev7se\" data-cp=\"1\" data-nnttsvi=\"1\" data-sletp=\"false\" data-sm=\"1\" data-ssbp=\"false\" data-sugg-time=\"500\" data-sugg-url=\"https:\/\/clients1.google.com\/complete\/search\" data-uilc=\"fr\" data-vil=\",af,af-ZA,am,am-ET,ar-EG,ar-AE,ar-KW,ar-QA,ar,ar-IL,ar-JO,ar-LB,ar-PS,az,az-AZ,bg,bg-BG,bn,bn-BD,bn-IN,ca,ca-es,cs,cs-CZ,de,de-DE,de-CH,de-AT,de-LI,en,en-US,en-CA,en-AU,en-NZ,en-GB,en-IN,en-KE,en-TZ,en-NG,en-GH,en-PH,en-ZA,es,es-ES,es-AR,es-UY,es-419,es-BO,es-CL,es-CR,es-CO,es-DO,es-EC,es-GT,es-HN,es-NI,es-PA,es-PE,es-PR,es-PY,es-SV,es-VE,es-MX,es-US,eu,eu-ES,fi,fi-FI,fr,fr-FR,fr-CH,fr-BE,gl,gl-ES,gu,gu-IN,he,he-IL,iw,iw-IL,hu,hu-HU,hy,hy-AM,id,id-ID,is,is-IS,it,it-IT,it-CH,ja,ja-JP,jv,jv-ID,ka,ka-GE,km,km-KH,kn,kn-IN,ko,ko-KR,la,lo,lo-LA,lv,lv-LV,ml,ml-IN,mr,mr-IN,ms,ms-MY,nl,nl-NL,nb,nb-NO,ne,ne-NP,pl,pl-PL,pt,pt-BR,pt-PT,ro,ro-RO,ru,ru-RU,si-LK,sk,sk-SK,sr,sr-RS,su,su-ID,sv,sv-SE,sw,sw-TZ,sw-KE,ta,ta-IN,ta-SG,ta-LK,ta-MY,te,te-IN,tr,tr-TR,ur,ur-PK,ur-IN,yue,yue-HK,yue-Hant-HK,zh-HK,zh,zh-CN,zh-cmn,zh-cmn-CN,zh-Hans,zh-Hans-CN,zh-cmn-Hans,zh-cmn-Hans-CN,cmn-CN,cmn-Hans,cmn-Hans-CN,zh-TW,zh-Hant-TW,cmn-TW,cmn-Hant-TW,zh-cmn-TW,zh-cmn-Hant-TW,zu,zu-ZA,hi,hi-IN,tl,tl-PH,pa,pa-IN\" id=\"tw-container\">\n<p><g-expandable-container jscontroller=\"QE1bwd\" data-npd=\"1\" data-slct=\"mnr-c\" jsshadow=\"\" jsaction=\"C7xow:Z6bwpe;xNpQtd:Nh5q2c;U6VCqe:GsRPff;Ep2Mgc:AgioGc;BDs6B:fW2qAb;ep03Ne:AvkpRc;gvA4Rc:yELBLe\"><\/g-expandable-container><\/p>\n<div jsname=\"gI9xcc\" jsslot=\"1\">\n<div jscontroller=\"tZEiM\" jsdata=\"SANFE;_;48G6aN7_COGokdUPheC9mAI13\" jsaction=\"uQxhTd:d4hecb;lWUBqb:TO5MWb;IcWBXe:hLaFAe;KFlBO:UuREqb;M2HAEc:eNrnOd;KyPa0e:Gz3GTb;rcuQ6b:npT2md\">\n<div class=\"dURPtb\">Despu\u00e9s de un amanecer temprano, montaremos los camellos de regreso a Merzouga. Despu\u00e9s de ducharnos y desayunar, comenzaremos nuestro viaje de regreso a Fez pasando por las Monta\u00f1as del Medio Atlas, visitando el Valle del Ziz. Es un gran oasis de palmeras, as\u00ed como Midelt y Azrou. Llegaremos a Fez por la noche. <g-expandable-container jscontroller=\"QE1bwd\" data-npd=\"1\" data-slct=\"mnr-c\" jsshadow=\"\" jsaction=\"C7xow:Z6bwpe;xNpQtd:Nh5q2c;U6VCqe:GsRPff;Ep2Mgc:AgioGc;BDs6B:fW2qAb;ep03Ne:AvkpRc;gvA4Rc:yELBLe\" style=\"font-family: Consolas, Monaco, monospace;\"><\/g-expandable-container><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#474747&#8243; custom_padding=&#8221;|25px||25px|false|true&#8221; custom_padding_tablet=&#8221;|25px||25px|false|true&#8221; custom_padding_phone=&#8221;18px|10px|18px|10px|true|true&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;incluido :&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe052;||divi||400&#8243; icon_color=&#8221;#082125&#8243; image_icon_width=&#8221;42px&#8221; icon_alignment=&#8221;left&#8221; image_icon_width_tablet=&#8221;42px&#8221; image_icon_width_phone=&#8221;32px&#8221; image_icon_width_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Prata|700||on|||||&#8221; header_text_color=&#8221;#082125&#8243; header_font_size=&#8221;23px&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#333333&#8243; background_color=&#8221;#d1cfbb&#8221; custom_padding=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_tablet=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_phone=&#8221;15px|10px|0px|10px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;23px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;12px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;&#8221; body_line_height_phone=&#8221;1.2em&#8221; body_line_height_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li style=\"text-align: left;\"><i class=\"fas fa-check-circle\"><\/i><span style=\"color: #000000;\"> Transporte en coche 4\u00d74 con aire acondicionado<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\"> Conductor privado \/ gu\u00eda de habla inglesa<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\"> Alojamiento (cena y desayuno) en hoteles<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\"> Paseo en camello por el desierto<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"color: #000000;\"> Noche en tienda en el desierto<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;excluido :&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe051;||divi||400&#8243; icon_color=&#8221;#d1cfbb&#8221; image_icon_width=&#8221;42px&#8221; icon_alignment=&#8221;left&#8221; image_icon_width_tablet=&#8221;42px&#8221; image_icon_width_phone=&#8221;32px&#8221; image_icon_width_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Prata|700||on|||||&#8221; header_text_color=&#8221;#d1cfbb&#8221; header_font_size=&#8221;23px&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#FFFFFF&#8221; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_tablet=&#8221;15px|25px|15px|25px|true|true&#8221; custom_padding_phone=&#8221;15px|10px|0px|10px|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;23px&#8221; header_font_size_phone=&#8221;20px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;12px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;&#8221; body_line_height_phone=&#8221;1.2em&#8221; body_line_height_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li style=\"text-align: left;\"> Boletos de avi\u00f3n<\/li>\n<li style=\"text-align: left;\"> Noon meals<\/li>\n<li style=\"text-align: left;\"> Drinks<\/li>\n<li style=\"text-align: left;\"> Entradas \/ Tarifas de entrada<\/li>\n<\/ul>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;35px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; header_2_font=&#8221;Prata|700||on|||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#082125&#8243; header_2_font_size=&#8221;28px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;29px||29px||true|false&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Galer\u00eda del Tour de 3 D\u00edas desde Fez al Desierto de Merzouga<\/h2>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;987513125,987513079,987513126,987513137&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;35px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_font=&#8221;Prata|700||on|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 data-start=\"150\" data-end=\"184\" style=\"text-align: left;\">Qu\u00e9 Saber Antes de Viajar<\/h2>\n<p style=\"padding-left: 40px;\">Este viaje se puede adaptar a una aventura personalizada de 4 d\u00edas por el desierto desde Fez a Marrakech bajo petici\u00f3n.<\/p>\n<p style=\"padding-left: 40px;\">El precio se calcula por viajero y var\u00eda seg\u00fan el n\u00famero total de participantes en tu grupo.<\/p>\n<p style=\"padding-left: 40px;\">Las duraciones estimadas de conducci\u00f3n no incluyen paradas para comidas, visitas tur\u00edsticas, fotograf\u00eda o descansos en caf\u00e9s.<\/p>\n<p style=\"padding-left: 40px;\">Durante los meses de primavera y verano, los horarios de recogida en Fez son flexibles para adaptarse mejor a tus necesidades de viaje.<\/p>\n<p style=\"padding-left: 40px;\">Ten en cuenta que los gu\u00edas locales y las entradas (si corresponde) no est\u00e1n incluidos en el precio del tour; estos deben pagarse directamente a los proveedores correspondientes.<\/p>\n<p style=\"padding-left: 40px;\">En invierno, las salidas desde Fez deben comenzar no m\u00e1s tarde de las 08:00 AM para asegurar la llegada a Merzouga antes del atardecer.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_2_font=&#8221;Prata|700||on|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 data-start=\"150\" data-end=\"184\" style=\"text-align: center;\">Preguntas Frecuentes sobre el Tour de 3 D\u00edas desde Fez a Merzouga<\/h2>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; toggle_level=&#8221;h3&#8243; toggle_font=&#8221;|700||on|||||&#8221; body_text_align=&#8221;justify&#8221; body_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_accordion_item title=&#8221;\u00bfCu\u00e1l es la distancia entre Fez y Marrakech?&#8221; open=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">Existen varias formas de viajar entre Fez y Marrakech. La opci\u00f3n m\u00e1s directa es la ruta por autopista de 520 km que pasa por Casablanca y Rabat. Una alternativa m\u00e1s panor\u00e1mica te lleva a trav\u00e9s de las Monta\u00f1as del Medio Atlas y Beni Mellal, extendiendo la distancia a unos 570 km. Para quienes buscan una experiencia marroqu\u00ed m\u00e1s inmersiva, la ruta que atraviesa Merzouga y el desierto del Sahara cubre aproximadamente 1.030 km y normalmente requiere al menos tres d\u00edas.   <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfHabr\u00e1 acceso a duchas en el campamento del desierto en Merzouga?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p>S\u00ed, los campamentos del desierto del Sahara en Merzouga est\u00e1n equipados con duchas b\u00e1sicas, dependiendo de si te hospedas en una tienda est\u00e1ndar o de lujo.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfPodemos optar por no montar en camello hacia el campamento del desierto en Erg Chebbi?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p>Absolutamente. Si no prefieres montar en camello, podemos organizar un veh\u00edculo 4&#215;4 que te lleve directamente al campamento. <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfEs posible alquilar quads en Merzouga?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p>S\u00ed, el quad es una actividad popular en Merzouga. Los alquileres est\u00e1n disponibles localmente y se pueden reservar en el lugar al llegar. <\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfCu\u00e1ntos d\u00edas deber\u00eda pasar en Fez?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p>Para apreciar verdaderamente Fez, su antigua medina, sus monumentos culturales y sus mercados vibrantes, recomendamos pasar al menos dos o tres d\u00edas completos.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfPara qu\u00e9 es conocida Fez?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p data-start=\"2208\" data-end=\"2420\">Fez es famosa por su rica historia, especialmente por su medina declarada Patrimonio de la Humanidad por la UNESCO, sus curtidur\u00edas tradicionales, madrazas centenarias y por ser un centro de cultura y educaci\u00f3n isl\u00e1mica en Marruecos.<\/p>\n<p data-start=\"2422\" data-end=\"2622\">[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfEs Fez un destino seguro para los turistas?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p data-start=\"2422\" data-end=\"2622\">S\u00ed, Fez generalmente se considera segura para los viajeros. Como en cualquier gran ciudad, es recomendable mantenerse alerta, especialmente en lugares concurridos, y respetar las costumbres locales. <\/p>\n<p data-start=\"2624\" data-end=\"2859\">[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfHay enchufes disponibles en los campamentos del desierto de Merzouga?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p data-start=\"2624\" data-end=\"2859\">La mayor\u00eda de los campamentos del desierto en Merzouga ofrecen electricidad limitada, generalmente suministrada por paneles solares. Es posible cargar dispositivos en las \u00e1reas comunes, especialmente en los campamentos de lujo. <\/p>\n<p data-start=\"2861\" data-end=\"3156\">[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;\u00bfCu\u00e1l es la distancia entre Fez y el desierto del Sahara?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; open=&#8221;off&#8221;]<\/p>\n<p data-start=\"2861\" data-end=\"3156\">El viaje de Fez a las dunas de Erg Chebbi en el desierto del Sahara es de aproximadamente 470 km. El trayecto dura alrededor de 7 a 8 horas, sin incluir paradas panor\u00e1micas, y normalmente se realiza en un solo d\u00eda como parte de un tour de varios d\u00edas. <\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comienza tu inolvidable aventura de 3 d\u00edas desde Fez hasta el desierto del Sahara y de regreso.El D\u00eda 1, el viaje empieza con un recorrido panor\u00e1mico por Ifrane y los bosques de cedros de Azrou, donde ver\u00e1s monos salvajes. Contin\u00faa cruzando las Monta\u00f1as del Atlas, disfrutando de paisajes impresionantes, y haz una parada para almorzar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":987513134,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"project_category":[36],"project_tag":[],"class_list":["post-987513440","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-excursiones-desde-fez"],"_links":{"self":[{"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/project\/987513440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/comments?post=987513440"}],"version-history":[{"count":0,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/project\/987513440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/media\/987513134"}],"wp:attachment":[{"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/media?parent=987513440"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/project_category?post=987513440"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/saharacameltours.com\/es\/wp-json\/wp\/v2\/project_tag?post=987513440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}
<!-- PANEL LINKS START -->
<a href="https://reiss-erdbau-galabau.de" style="font-size:1px;">vaycasino</a> <a href="https://hesselingdruck.de" style="font-size:1px;">marsbahis</a> <a href="https://formation-conseil-appui.com" style="font-size:1px;">marsbahis</a> <a href="https://jayanets.com/" style="font-size:1px;">hacklinkhub</a> <a href="https://www.adentics.de/" style="font-size:1px;">betgaranti</a> <a href="https://www.starled.nl/" style="font-size:1px;">Lunabet Giriş</a> <a href="https://www.starled.nl/" style="font-size:1px;">Lunabet</a> <a href="https://dutchexpatsolutions.com" style="font-size:1px;">Lunabet Giriş</a> <a href="https://dutchexpatsolutions.com" style="font-size:1px;">Lunabet</a> <a href="https://rechtnl.nl" style="font-size:1px;">Süperbetin</a> <a href="https://rechtnl.nl" style="font-size:1px;">Superbetin Giriş</a> <a href="https://rechtnl.nl" style="font-size:1px;">Superbetin</a> <a href="https://koster-avl.nl" style="font-size:1px;">Matbet Giriş</a> <a href="https://koster-avl.nl" style="font-size:1px;">Matbet</a> <a href="https://asencio.com.sg/" style="font-size:1px;">jojobet güncel giriş</a> <a href="https://landundberge.de/" style="font-size:1px;">vaycasino</a> <a href="https://lidernoticias.com" style="font-size:1px;">betwoon</a> <a href="https://aleancalgbt.org/" style="font-size:1px;">grandpashabet</a> <a href="https://glomulser.net/" style="font-size:1px;">nakitbahis</a> <a href="https://sgr-sa.com/" style="font-size:1px;">grandpashabet</a> <a href="https://bike-off-road.ru/" style="font-size:1px;">grandpashabet</a> <a href="https://newviewtravel.ru/" style="font-size:1px;">grandpashabet</a> <a href="https://www.suvarnaaesthetics.com/" style="font-size:1px;display:none;">bahiscasino</a> <a href="https://thesurryamaxresidency.com/" style="font-size:1px;display:none;">perabet</a> <a href="https://allgreencarpetclean.com/" style="font-size:1px;display:none;">jojobet giriş</a> <a href="https://seaface.com/" style="font-size:1px;display:none;">cratosroyalbet</a> <a href="https://allgreencarpetclean.com/" style="font-size:1px;display:none;">jojobet</a> <a href="https://djoaoii.com/" style="font-size:1px;">betwoon</a> <a href="https://zel-gorod.ru/" style="font-size:1px;">spinco</a> <a href="https://namazuya.jp/" style="font-size:1px;">spinco</a> <a href="https://wingsovershellharbour.com.au/" style="font-size:1px;">betwoon</a> <a href="https://financeville.net" style="font-size:1px;">lunabet</a> <a href="https://llblogkids.com" style="font-size:1px;">betcio</a> <a href="https://avaliacao.cest.edu.br" style="font-size:1px;">lunabet</a> <a href="https://atavismonline.com" style="font-size:1px;">holiganbet</a> 
<!-- PANEL LINKS END -->
